{"id":3944,"date":"2022-09-15T14:08:41","date_gmt":"2022-09-15T08:38:41","guid":{"rendered":"https:\/\/dev.dightinfotech.com\/scolio_life\/home\/"},"modified":"2024-04-01T20:56:34","modified_gmt":"2024-04-01T15:26:34","slug":"home","status":"publish","type":"page","link":"https:\/\/scoliometer.app\/id\/","title":{"rendered":"BERANDA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"my-templates\/home.php","meta":{"footnotes":""},"class_list":["post-3944","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia<\/title>\n<meta name=\"description\" content=\"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scoliometer.app\/id\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia\" \/>\n<meta property=\"og:description\" content=\"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scoliometer.app\/id\/\" \/>\n<meta property=\"og:site_name\" content=\"Scoliometer App\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/scoliolife\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-01T15:26:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@drkevinlau\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scoliometer.app\\\/id\\\/\",\"url\":\"https:\\\/\\\/scoliometer.app\\\/id\\\/\",\"name\":\"BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#website\"},\"datePublished\":\"2022-09-15T08:38:41+00:00\",\"dateModified\":\"2024-04-01T15:26:34+00:00\",\"description\":\"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scoliometer.app\\\/id\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scoliometer.app\\\/id\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scoliometer.app\\\/id\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/scoliometer.app\\\/id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BERANDA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#website\",\"url\":\"https:\\\/\\\/scoliometer.app\\\/\",\"name\":\"Scoliometer App\",\"description\":\"Scoliometer App by ScolioLife\u2122\",\"publisher\":{\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scoliometer.app\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#organization\",\"name\":\"ScolioLife Pte Ltd\",\"url\":\"https:\\\/\\\/scoliometer.app\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scoliometer.app\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ScolioLife-LogoRectangle-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/scoliometer.app\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/ScolioLife-LogoRectangle-scaled.jpg\",\"width\":2560,\"height\":819,\"caption\":\"ScolioLife Pte Ltd\"},\"image\":{\"@id\":\"https:\\\/\\\/scoliometer.app\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/scoliolife\",\"https:\\\/\\\/x.com\\\/drkevinlau\",\"https:\\\/\\\/www.instagram.com\\\/scoliolife\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia","description":"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scoliometer.app\/id\/","og_locale":"id_ID","og_type":"article","og_title":"BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia","og_description":"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.","og_url":"https:\/\/scoliometer.app\/id\/","og_site_name":"Scoliometer App","article_publisher":"https:\/\/www.facebook.com\/scoliolife","article_modified_time":"2024-04-01T15:26:34+00:00","twitter_card":"summary_large_image","twitter_site":"@drkevinlau","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/scoliometer.app\/id\/","url":"https:\/\/scoliometer.app\/id\/","name":"BERANDA | Aplikasi Skoliometer untuk Skoliosis di iOS dan Android | Indonesia","isPartOf":{"@id":"https:\/\/scoliometer.app\/#website"},"datePublished":"2022-09-15T08:38:41+00:00","dateModified":"2024-04-01T15:26:34+00:00","description":"Aplikasi Skoliometer untuk memantau skoliosis Anda dalam kenyamanan rumah atau klinik Anda sendiri. Pantau kondisi skoliosis Anda dengan aman dan akurat.","breadcrumb":{"@id":"https:\/\/scoliometer.app\/id\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scoliometer.app\/id\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/scoliometer.app\/id\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/scoliometer.app\/id\/"},{"@type":"ListItem","position":2,"name":"BERANDA"}]},{"@type":"WebSite","@id":"https:\/\/scoliometer.app\/#website","url":"https:\/\/scoliometer.app\/","name":"Scoliometer App","description":"Scoliometer App by ScolioLife\u2122","publisher":{"@id":"https:\/\/scoliometer.app\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scoliometer.app\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/scoliometer.app\/#organization","name":"ScolioLife Pte Ltd","url":"https:\/\/scoliometer.app\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/scoliometer.app\/#\/schema\/logo\/image\/","url":"https:\/\/scoliometer.app\/wp-content\/uploads\/2022\/12\/ScolioLife-LogoRectangle-scaled.jpg","contentUrl":"https:\/\/scoliometer.app\/wp-content\/uploads\/2022\/12\/ScolioLife-LogoRectangle-scaled.jpg","width":2560,"height":819,"caption":"ScolioLife Pte Ltd"},"image":{"@id":"https:\/\/scoliometer.app\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/scoliolife","https:\/\/x.com\/drkevinlau","https:\/\/www.instagram.com\/scoliolife\/"]}]}},"_links":{"self":[{"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/pages\/3944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/comments?post=3944"}],"version-history":[{"count":4,"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/pages\/3944\/revisions"}],"predecessor-version":[{"id":11496,"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/pages\/3944\/revisions\/11496"}],"wp:attachment":[{"href":"https:\/\/scoliometer.app\/id\/wp-json\/wp\/v2\/media?parent=3944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}